{"id":73,"count":1,"description":"","link":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio_cat\/tv\/","name":"TV","slug":"tv","taxonomy":"portfolio_category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/marcelocortazio.com.br\/index.php\/wp-json\/wp\/v2\/portfolio_category\/73","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelocortazio.com.br\/index.php\/wp-json\/wp\/v2\/portfolio_category"}],"about":[{"href":"https:\/\/marcelocortazio.com.br\/index.php\/wp-json\/wp\/v2\/taxonomies\/portfolio_category"}],"wp:post_type":[{"href":"https:\/\/marcelocortazio.com.br\/index.php\/wp-json\/wp\/v2\/portfolio?portfolio_category=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}