{"id":84057,"date":"2022-07-27T01:21:58","date_gmt":"2022-07-27T01:21:58","guid":{"rendered":"https:\/\/marcelocortazio.com.br\/?post_type=portfolio&#038;p=84057"},"modified":"2024-04-05T21:54:06","modified_gmt":"2024-04-05T21:54:06","slug":"bat-carpool","status":"publish","type":"portfolio","link":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/","title":{"rendered":"BAT Carpool"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;5&#8243; bottom_padding=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column column_width_use_pixel=&#8221;yes&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243; column_width_pixel=&#8221;900&#8243;][vc_custom_heading auto_text=&#8221;yes&#8221; text_color=&#8221;color-jevc&#8221; heading_semantic=&#8221;h1&#8243; text_font=&#8221;font-504674&#8243; text_size=&#8221;h1&#8243; text_weight=&#8221;100&#8243;]BAT Carpool[\/vc_custom_heading][vc_custom_heading text_color=&#8221;color-wvjs&#8221; heading_semantic=&#8221;h1&#8243; text_font=&#8221;font-143967&#8243; text_size=&#8221;fontsize-156538&#8243; text_weight=&#8221;100&#8243; uncode_shortcode_id=&#8221;436171&#8243; text_color_type=&#8221;uncode-palette&#8221;]Formato de entrevista casual desenvolvido para a British American Tobacco. Inspirado no programa de TV Carpool Karaoke, o Diretor de Marketing da empresa e um promotor de vendas trocam experi\u00eancias durante uma rota comercial.[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/1&#8243;][vc_single_image media=&#8221;84069&#8243; media_width_percent=&#8221;100&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;5&#8243; bottom_padding=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column column_width_use_pixel=&#8221;yes&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":84088,"parent":0,"menu_order":0,"template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_monsterinsights_skip_tracking":false,"footnotes":""},"portfolio_category":[69],"class_list":["post-84057","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-branded-entertainment"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"BAT Carpool Formato de entrevista casual desenvolvido para a British American Tobacco. Inspirado no programa de TV Carpool Karaoke, o Diretor de Marketing da empresa e um promotor de vendas trocam experi\u00eancias durante uma rota comercial.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"marcelo.cortazio\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Marcelo Cortazio - Storytelling como sistema de influ\u00eancia, autoridade e receita. Para marcas e l\u00edderes.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"BAT Carpool - Marcelo Cortazio\" \/>\n\t\t<meta property=\"og:description\" content=\"BAT Carpool Formato de entrevista casual desenvolvido para a British American Tobacco. Inspirado no programa de TV Carpool Karaoke, o Diretor de Marketing da empresa e um promotor de vendas trocam experi\u00eancias durante uma rota comercial.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-07-27T01:21:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-05T21:54:06+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"BAT Carpool - Marcelo Cortazio\" \/>\n\t\t<meta name=\"twitter:description\" content=\"BAT Carpool Formato de entrevista casual desenvolvido para a British American Tobacco. Inspirado no programa de TV Carpool Karaoke, o Diretor de Marketing da empresa e um promotor de vendas trocam experi\u00eancias durante uma rota comercial.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio\\\/bat-carpool\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelocortazio.com.br\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio\\\/#listItem\",\"name\":\"Portfolio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio\\\/#listItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio_cat\\\/branded-entertainment\\\/#listItem\",\"name\":\"Branded Entertainment\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio_cat\\\/branded-entertainment\\\/#listItem\",\"position\":3,\"name\":\"Branded Entertainment\",\"item\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio_cat\\\/branded-entertainment\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio\\\/bat-carpool\\\/#listItem\",\"name\":\"BAT Carpool\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio\\\/#listItem\",\"name\":\"Portfolio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio\\\/bat-carpool\\\/#listItem\",\"position\":4,\"name\":\"BAT Carpool\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio_cat\\\/branded-entertainment\\\/#listItem\",\"name\":\"Branded Entertainment\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/#organization\",\"name\":\"Marcelo Cortazio\",\"description\":\"Storytelling como sistema de influ\\u00eancia, autoridade e receita. Para marcas e l\\u00edderes.\",\"url\":\"https:\\\/\\\/marcelocortazio.com.br\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/author\\\/marcelo-cortazio\\\/#author\",\"url\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/author\\\/marcelo-cortazio\\\/\",\"name\":\"marcelo.cortazio\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio\\\/bat-carpool\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0dc8d4575ae0ddf73ed6899235520ea68c272112b1508bc22b3d46255893a700?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"marcelo.cortazio\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio\\\/bat-carpool\\\/#webpage\",\"url\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio\\\/bat-carpool\\\/\",\"name\":\"BAT Carpool - Marcelo Cortazio\",\"description\":\"BAT Carpool Formato de entrevista casual desenvolvido para a British American Tobacco. Inspirado no programa de TV Carpool Karaoke, o Diretor de Marketing da empresa e um promotor de vendas trocam experi\\u00eancias durante uma rota comercial.\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio\\\/bat-carpool\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/author\\\/marcelo-cortazio\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/author\\\/marcelo-cortazio\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/marcelocortazio.com.br\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Screen-Shot-2021-07-26-at-10.19.14-PM-1.png\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio\\\/bat-carpool\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/index.php\\\/portfolio\\\/bat-carpool\\\/#mainImage\"},\"datePublished\":\"2022-07-27T01:21:58+00:00\",\"dateModified\":\"2024-04-05T21:54:06+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/#website\",\"url\":\"https:\\\/\\\/marcelocortazio.com.br\\\/\",\"name\":\"Marcelo Cortazio\",\"description\":\"Storytelling como sistema de influ\\u00eancia, autoridade e receita. Para marcas e l\\u00edderes.\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelocortazio.com.br\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"BAT Carpool - Marcelo Cortazio","description":"BAT Carpool Formato de entrevista casual desenvolvido para a British American Tobacco. Inspirado no programa de TV Carpool Karaoke, o Diretor de Marketing da empresa e um promotor de vendas trocam experi\u00eancias durante uma rota comercial.","canonical_url":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/marcelocortazio.com.br#listItem","position":1,"name":"Home","item":"https:\/\/marcelocortazio.com.br","nextItem":{"@type":"ListItem","@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/#listItem","name":"Portfolio"}},{"@type":"ListItem","@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/#listItem","position":2,"name":"Portfolio","item":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/","nextItem":{"@type":"ListItem","@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio_cat\/branded-entertainment\/#listItem","name":"Branded Entertainment"},"previousItem":{"@type":"ListItem","@id":"https:\/\/marcelocortazio.com.br#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio_cat\/branded-entertainment\/#listItem","position":3,"name":"Branded Entertainment","item":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio_cat\/branded-entertainment\/","nextItem":{"@type":"ListItem","@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/#listItem","name":"BAT Carpool"},"previousItem":{"@type":"ListItem","@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/#listItem","name":"Portfolio"}},{"@type":"ListItem","@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/#listItem","position":4,"name":"BAT Carpool","previousItem":{"@type":"ListItem","@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio_cat\/branded-entertainment\/#listItem","name":"Branded Entertainment"}}]},{"@type":"Organization","@id":"https:\/\/marcelocortazio.com.br\/#organization","name":"Marcelo Cortazio","description":"Storytelling como sistema de influ\u00eancia, autoridade e receita. Para marcas e l\u00edderes.","url":"https:\/\/marcelocortazio.com.br\/"},{"@type":"Person","@id":"https:\/\/marcelocortazio.com.br\/index.php\/author\/marcelo-cortazio\/#author","url":"https:\/\/marcelocortazio.com.br\/index.php\/author\/marcelo-cortazio\/","name":"marcelo.cortazio","image":{"@type":"ImageObject","@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/0dc8d4575ae0ddf73ed6899235520ea68c272112b1508bc22b3d46255893a700?s=96&d=mm&r=g","width":96,"height":96,"caption":"marcelo.cortazio"}},{"@type":"WebPage","@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/#webpage","url":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/","name":"BAT Carpool - Marcelo Cortazio","description":"BAT Carpool Formato de entrevista casual desenvolvido para a British American Tobacco. Inspirado no programa de TV Carpool Karaoke, o Diretor de Marketing da empresa e um promotor de vendas trocam experi\u00eancias durante uma rota comercial.","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/marcelocortazio.com.br\/#website"},"breadcrumb":{"@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/#breadcrumblist"},"author":{"@id":"https:\/\/marcelocortazio.com.br\/index.php\/author\/marcelo-cortazio\/#author"},"creator":{"@id":"https:\/\/marcelocortazio.com.br\/index.php\/author\/marcelo-cortazio\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/marcelocortazio.com.br\/wp-content\/uploads\/2021\/07\/Screen-Shot-2021-07-26-at-10.19.14-PM-1.png","@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/#mainImage"},"datePublished":"2022-07-27T01:21:58+00:00","dateModified":"2024-04-05T21:54:06+00:00"},{"@type":"WebSite","@id":"https:\/\/marcelocortazio.com.br\/#website","url":"https:\/\/marcelocortazio.com.br\/","name":"Marcelo Cortazio","description":"Storytelling como sistema de influ\u00eancia, autoridade e receita. Para marcas e l\u00edderes.","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/marcelocortazio.com.br\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Marcelo Cortazio - Storytelling como sistema de influ\u00eancia, autoridade e receita. Para marcas e l\u00edderes.","og:type":"article","og:title":"BAT Carpool - Marcelo Cortazio","og:description":"BAT Carpool Formato de entrevista casual desenvolvido para a British American Tobacco. Inspirado no programa de TV Carpool Karaoke, o Diretor de Marketing da empresa e um promotor de vendas trocam experi\u00eancias durante uma rota comercial.","og:url":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/","article:published_time":"2022-07-27T01:21:58+00:00","article:modified_time":"2024-04-05T21:54:06+00:00","twitter:card":"summary","twitter:title":"BAT Carpool - Marcelo Cortazio","twitter:description":"BAT Carpool Formato de entrevista casual desenvolvido para a British American Tobacco. Inspirado no programa de TV Carpool Karaoke, o Diretor de Marketing da empresa e um promotor de vendas trocam experi\u00eancias durante uma rota comercial."},"aioseo_meta_data":{"post_id":"84057","title":"#post_title #separator_sa #site_title","description":"#post_excerpt","keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-07-27 01:21:59","updated":"2025-08-04 01:15:58","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/marcelocortazio.com.br\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/\" title=\"Portfolio\">Portfolio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/marcelocortazio.com.br\/index.php\/portfolio_cat\/branded-entertainment\/\" title=\"Branded Entertainment\">Branded Entertainment<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBAT Carpool\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/marcelocortazio.com.br"},{"label":"Portfolio","link":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/"},{"label":"Branded Entertainment","link":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio_cat\/branded-entertainment\/"},{"label":"BAT Carpool","link":"https:\/\/marcelocortazio.com.br\/index.php\/portfolio\/bat-carpool\/"}],"_links":{"self":[{"href":"https:\/\/marcelocortazio.com.br\/index.php\/wp-json\/wp\/v2\/portfolio\/84057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelocortazio.com.br\/index.php\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/marcelocortazio.com.br\/index.php\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/marcelocortazio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":5,"href":"https:\/\/marcelocortazio.com.br\/index.php\/wp-json\/wp\/v2\/portfolio\/84057\/revisions"}],"predecessor-version":[{"id":130804,"href":"https:\/\/marcelocortazio.com.br\/index.php\/wp-json\/wp\/v2\/portfolio\/84057\/revisions\/130804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelocortazio.com.br\/index.php\/wp-json\/wp\/v2\/media\/84088"}],"wp:attachment":[{"href":"https:\/\/marcelocortazio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=84057"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/marcelocortazio.com.br\/index.php\/wp-json\/wp\/v2\/portfolio_category?post=84057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}